{"id":400,"name":"John Penek","url":"","description":"","link":"https:\/\/courses.bowdoin.edu\/english-1038-spring-2017\/author\/jhpenek\/","slug":"jhpenek","meta":[],"user_switching_url":null,"_links":{"self":[{"href":"https:\/\/courses.bowdoin.edu\/english-1038-spring-2017\/wp-json\/wp\/v2\/users\/400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/courses.bowdoin.edu\/english-1038-spring-2017\/wp-json\/wp\/v2\/users"}]}}